{"id":4221,"date":"2019-12-13T11:17:28","date_gmt":"2019-12-13T11:17:28","guid":{"rendered":"https:\/\/chateau-marcel.com\/historia-de-los-cataros\/"},"modified":"2021-10-23T13:24:41","modified_gmt":"2021-10-23T13:24:41","slug":"historia-de-los-cataros","status":"publish","type":"page","link":"https:\/\/chateau-marcel.com\/es\/historia-de-los-cataros\/","title":{"rendered":"Historia de los c\u00e1taros"},"content":{"rendered":"\n<div class=\"wp-block-getwid-section alignfull alignfull getwid-margin-top-none getwid-margin-bottom-none\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-top-none getwid-padding-bottom-none getwid-padding-left-medium getwid-padding-right-medium getwid-padding-mobile-left-small getwid-padding-mobile-right-small\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-getwid-advanced-heading is-style-style-1 has-custom-font-size\" style=\"font-size:12px;margin-bottom:0px\"><p class=\"wp-block-getwid-advanced-heading__content\" style=\"letter-spacing:0.1em\"> Un rico patrimonio en el coraz\u00f3n de la Minervois francesa<\/p><\/div>\n\n\n\n<div class=\"wp-block-getwid-advanced-heading is-style-default\" style=\"margin-top:10px\"><h2 class=\"wp-block-getwid-advanced-heading__content\">La historia de los c\u00e1taros en la zona de Languedoc<\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Los c\u00e1taros (tambi\u00e9n conocidos como cathari del griego Katharoi para los \u00abpuros\u00bb) eran una secta religiosa medieval dualista del sur de Francia que floreci\u00f3 en el siglo XII d.C. y desafi\u00f3 la autoridad de la Iglesia Cat\u00f3lica. Tambi\u00e9n eran conocidos como albigenses para la ciudad de Albi, que era un fuerte centro C\u00e1taro de creencias. Los sacerdotes c\u00e1taros viv\u00edan simplemente, no ten\u00edan posesiones, no impon\u00edan impuestos ni sanciones, y consideraban a hombres y mujeres como iguales; aspectos de la fe que apelaban a muchos en ese momento desilusionados con la Iglesia. Las creencias c\u00e1taros finalmente derivaron de la religi\u00f3n persa del Manique\u00edsmo, pero directamente de otra secta religiosa anterior de Bulgaria conocida como los Bogomils que mezclaban el Manique\u00edsmo con el cristianismo.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"500\" height=\"410\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/Cathars1.jpg\" alt=\"\" class=\"wp-image-4223 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/Cathars1.jpg 500w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/Cathars1-300x246.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Los registros de la Iglesia Cat\u00f3lica Romana los mencionan bajo varios nombres y en varios lugares. Los te\u00f3logos cat\u00f3licos debatieron consigo mismos durante siglos si los c\u00e1taros eran herejes cristianos o si no eran cristianos en absoluto. La pregunta aparentemente sigue abierta. Los Cat\u00f3licos romanos todav\u00eda se refieren a la Creencia C\u00e1tara como \u00abLa gran herej\u00eda\u00bb aunque la posici\u00f3n cat\u00f3lica oficial es que el Catarismo no es cristiano en absoluto.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Perfecti<\/em> \u2013 aquellos que hab\u00edan renunciado al mundo, los sacerdotes y obispos<\/li><li><em>Credentes<\/em> \u2013 creyentes que todav\u00eda interactuaban con el mundo pero trabajaban hacia la renuncia<\/li><li>Simpatizantes \u2013 no creyentes que ayudaron y apoyaron a las comunidades C\u00e1taras<\/li><\/ul><\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"611\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars-region-map-1024x611.jpg\" alt=\"\" class=\"wp-image-4228 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars-region-map-1024x611.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars-region-map-300x179.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars-region-map-768x458.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars-region-map-1170x698.jpg 1170w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars-region-map.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Los c\u00e1taros rechazaron las ense\u00f1anzas de la Iglesia Cat\u00f3lica como inmorales y la mayor\u00eda de los libros de la Biblia inspirados por Satan\u00e1s. Criticaron a la Iglesia en gran medida por la hipocres\u00eda, la codicia y la lascivia de su clero, y la adquisici\u00f3n de tierra y riqueza por parte de la Iglesia. No es de extra\u00f1ar que los c\u00e1taros fueran condenados como her\u00e9ticos por la Iglesia Cat\u00f3lica y masacrados en la Cruzada Albigensiana (1209-1229 d.C.) que tambi\u00e9n devast\u00f3 las ciudades, ciudades y cultura del sur de Francia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La religi\u00f3n floreci\u00f3 en una zona a menudo conocida como el Languedoc, ampliamente bordeada por el Mar Mediterr\u00e1neo, los Pirineos, y los r\u00edos Garona, Tarn y R\u00f3dano y correspondiente a la nueva regi\u00f3n francesa de Occitanie (o las antiguas regiones francesas de Languedoc-Rosell\u00f3n y Midi-Pyr\u00e9n\u00e9es)<\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"903\" height=\"1024\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars3-903x1024.jpg\" alt=\"\" class=\"wp-image-4233 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars3-903x1024.jpg 903w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars3-264x300.jpg 264w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars3-768x871.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars3-1170x1327.jpg 1170w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars3.jpg 1348w\" sizes=\"(max-width: 903px) 100vw, 903px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Las creencias Cat\u00f3ras inclu\u00edan:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>El reconocimiento del principio femenino en lo divino \u2013 Dios era tanto hombre como mujer. El aspecto femenino de Dios era Sof\u00eda, \u00absabidur\u00eda\u00bb). Esta creencia alent\u00f3 la igualdad de los sexos en las comunidades c\u00e1taros.<\/li><li>Metempsicosis (Reencarnaci\u00f3n) \u2013 un alma renacer\u00eda continuamente hasta que renunciara al mundo por completo y escapara de la encarnaci\u00f3n.<\/li><li>Dualidad C\u00f3smica \u2013 la existencia de dos poderosas deidades en el universo, una buena y otra malvada, que estaban en un estado de guerra constante. El prop\u00f3sito de la vida era servir al bien sirviendo a los dem\u00e1s y escapar del ciclo del renacimiento y la muerte para regresar a casa a Dios.<\/li><li>Vegetarianismo &#8211; aunque comer pescado se le permiti\u00f3 a <em>credentes<\/em> y simpatizantes.<\/li><li>Celibato para <em>perfecti<\/em> \u2013 celibato tambi\u00e9n fue alentado en general ya que se pensaba que cada persona nacida era s\u00f3lo otra pobre alma atrapada por el diablo en un cuerpo. El matrimonio en general se desanim\u00f3.<\/li><li>La dignidad del trabajo manual \u2013 todos los c\u00e1taros trabajaban, sacerdotes y laicos, muchos como tejedores. <\/li><li>El suicidio (conocido como el ritual de <em>la endura)<\/em>como una respuesta racional y digna bajo ciertas condiciones.<\/li><\/ul><\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"591\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2-1024x591.jpg\" alt=\"\" class=\"wp-image-4238 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2-1024x591.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2-300x173.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2-768x444.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2-1536x887.jpg 1536w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2-1170x676.jpg 1170w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cathars2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-normal-font-size wp-block-paragraph\">Como dualistas, los c\u00e1taros cre\u00edan en dos principios, un buen dios y su adversario maligno (como Dios y Satan\u00e1s del cristianismo convencional). El buen principio hab\u00eda creado todo lo inmaterial (bueno, permanente, inmutable) mientras que el mal principio hab\u00eda creado todo lo material (malo, temporal, perecedero). Los c\u00e1taros se llamaban simplemente cristianos; sus vecinos los distinguieron como \u00abbuenos cristianos\u00bb. La Iglesia Cat\u00f3lica los llamaba albigenses, o con menos frecuencia c\u00e1taros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los c\u00e1taros mantuvieron una jerarqu\u00eda de la Iglesia y practicaron una serie de ceremonias, pero rechazaron cualquier idea del sacerdocio o el uso de edificios de la iglesia. Se dividieron en creyentes ordinarios que dirig\u00edan vidas medievales ordinarias y un electo de Parfaits (hombres) y parfaites (mujeres) que dirig\u00edan vidas extremadamente asc\u00e9ticas pero a\u00fan trabajaban para su vida, generalmente en oficios manuales itinerantes como el tejido. Los c\u00e1taros cre\u00edan en la reencarnaci\u00f3n y se nega\u00edan a comer carne u otros productos animales. Eran estrictos con los mandamientos b\u00edblicos, en particular los que trataban de vivir en la pobreza, no decir mentiras, no matar y no jurar juramentos.<\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"976\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/CatharDoveweb-1024x976.jpg\" alt=\"\" class=\"wp-image-4243 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/CatharDoveweb-1024x976.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/CatharDoveweb-300x286.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/CatharDoveweb-768x732.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/CatharDoveweb-1170x1115.jpg 1170w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/CatharDoveweb.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">En el Languedoc, conocido en su momento por su alta cultura, tolerancia y\nliberalismo, la religi\u00f3n c\u00e1hara se arraig\u00f3 y gan\u00f3 m\u00e1s y m\u00e1s adherentes\ndurante el siglo XII. A principios del siglo XIII el catarismo era\nprobablemente la religi\u00f3n mayoritaria en la zona. Muchos textos cat\u00f3licos se refieren a la\npeligro de que reemplace completamente el catholismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El catarismo fue apoyado o al menos tolerado por la nobleza, as\u00ed como\nla gente com\u00fan. Esta fue una molestia m\u00e1s a la Iglesia Romana que\nconsiderado el sistema feudal para ser divinamente ordenado como el Orden Natural\n(A los c\u00e1taros no les gustaba el sistema feudal porque depend\u00eda de la toma de juramento).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de 1208, se libr\u00f3 una guerra de terror contra la poblaci\u00f3n ind\u00edgena\ndel Languedoc y sus gobernantes: Raymond VI de Toulouse, Raymond-Roger\nTrencavel, Raymond Roger de Foix en la primera generaci\u00f3n y Raymond VII de\nToulouse, Raymond Trencavel II y Roger Bernard II de Foix en el segundo\nGeneraci\u00f3n. Durante este per\u00edodo se estima que medio mill\u00f3n de hombres Languedoc, mujeres\ny los ni\u00f1os fueron masacrados, cat\u00f3licos y c\u00e1taros. Los cruzados asesinados\nlos lugare\u00f1os indiscriminadamente &#8211; en l\u00ednea con el famoso mandamiento judicial registrado\npor un cronista cisterciense como hablado por su compa\u00f1ero cisterciense, el abad\nal mando del ej\u00e9rcito cruzado en B\u00e9ziers.<\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"414\" height=\"532\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/montsegurweb.jpg\" alt=\"\" class=\"wp-image-4248 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/montsegurweb.jpg 414w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/montsegurweb-233x300.jpg 233w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Los Condes de Toulouse y sus aliados fueron despose\u00eddos y\nhumillado, y sus tierras m\u00e1s tarde anexionados a Francia. Educado y tolerante\nLos gobernantes de Languedoc fueron reemplazados por b\u00e1rbaros relativos; Dominic Guzm\u00e1n (m\u00e1s tarde\nSanto Domingo) fund\u00f3 la Orden Dominicana. En pocos a\u00f1os el primer papal\nLa Inquisici\u00f3n, tripulada por los dominicos, se estableci\u00f3 expl\u00edcitamente para\nlos \u00faltimos vestigios de resistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final del exterminio de los c\u00e1taros, la Iglesia romana hab\u00eda\nprueba de que una campa\u00f1a sostenida de genocidio puede funcionar. Tambi\u00e9n tuvo el precedente\nde una Cruzada interna dentro de la cristiandad, y la maquinaria de la primera\nestado policial moderno que podr\u00eda ser reconstruido para la Inquisici\u00f3n espa\u00f1ola,\ny de nuevo para m\u00e1s tarde Inquisiciones y genocidios. Chateaubriand se refiri\u00f3 a la\ncruzada como \u00abeste episodio abominable de nuestra historia\u00bb. Voltaire\nobserv\u00f3 que \u00abnunca hubo nada tan injusto como la guerra contra la\nAbigenzen\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda, todav\u00eda hay muchos ecos de influencias del per\u00edodo C\u00e1taro,\ndesde la geopol\u00edtica internacional hasta la cultura popular. Incluso hay c\u00e1taros\nvivos hoy, o al menos la gente que dice ser c\u00e1taros modernos. Hay\nvisitas hist\u00f3ricas de los sitios c\u00e1taros y tambi\u00e9n un florecimiento, aunque en gran medida\nsuperficial, la industria tur\u00edstica C\u00e1taro en el Languedoc, y especialmente en el\nDepartamento Aude.<\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 19%\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"180\" height=\"223\" src=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/montfort.jpg\" alt=\"\" class=\"wp-image-21893 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Sim\u00f3n de Montfort<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00edder de la cruzada contra los albigenses, dirigi\u00f3 esta guerra con valent\u00eda y crueldad. Ya se hab\u00eda distinguido por su valent\u00eda durante la Cuarta Cruzada. Representa el &#8216;puritanismo del norte&#8217;. Es el perfecto opuesto de su enemigo, el conde Raimundo VI de Toulouse, el s\u00edmbolo del \u00ablibertino sure\u00f1o\u00bb. Son el modelo del choque de las dos culturas.<\/p>\n<\/div><\/div>\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"295\" height=\"189\" src=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/castle.jpg\" alt=\"\" class=\"wp-image-21898 size-full\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/castle.jpg 295w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/castle-140x90.jpg 140w\" sizes=\"(max-width: 295px) 100vw, 295px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Minerve y catarismo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Por obediencia de los vizcondes de Carcasona en 1127, luego de B\u00e9ziers en 1171, Minerve pas\u00f3 a ser posesi\u00f3n del rey de Arag\u00f3n a partir de 1179.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios del siglo XIII, Minerve se convirti\u00f3 en lugar de paso y residencia de los c\u00e1taros. Como uno de los tres lugares estrat\u00e9gicos (junto con Termes y Lastours) que controlaban la regi\u00f3n, Minerve fue objeto de un asedio en 1210 (desde el 15 de junio) por los cruzados de Sim\u00f3n de Montfort.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se construy\u00f3 una m\u00e1quina de guerra (\u00abla Malevoisine\u00bb) al noroeste de la ciudad, cerca de la carretera cubierta, en la meseta rocosa que domina el cruce del Brian y el Cesse. Tras un fallido intento de destruir este trabuquete y varios d\u00edas de conversaciones entre Guillaume de Minerve y Sim\u00f3n de Montfort, los sitiados solo pudieron capitular, tras dos meses de estrangulamiento de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neg\u00e1ndose a renunciar a su fe, los c\u00e1taros de Minerve terminaron quemados en la hoguera: casi 140 personas perecieron en las llamas que presagiaban el terror de la Inquisici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guillaume de Minerve y su hijo estuvieron entre los que resistieron.<br\/><br\/>* CESSERAS: Pierre-Raimond de Cesseras fue encarcelado por el crimen de herej\u00eda por el terrible fraile Ferrarius. Su hijo Bernard Arnaud fue declarado faidit y sus nietos Guillaume y Pilfort fueron despose\u00eddos para siempre. Despu\u00e9s de la conquista, Saint-Louis dio Cesseras en la asignaci\u00f3n a Trencavel. <\/p>\n<\/div><\/div>\n\n<hr class=\"wp-block-separator\"\/>\n\n<div class=\"wp-block-getwid-section alignfull alignfull getwid-margin-top-none getwid-margin-bottom-none\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-top-none getwid-padding-bottom-none getwid-padding-left-medium getwid-padding-right-medium getwid-padding-mobile-left-small getwid-padding-mobile-right-small\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-getwid-advanced-heading is-style-style-1 has-custom-font-size\" style=\"font-size:12px;margin-bottom:0px\"><p class=\"wp-block-getwid-advanced-heading__content\" style=\"letter-spacing:0.1em\">Ch\u00e2teau Marcel tiene una rica historia\u2026<\/p><\/div>\r\n\n\n\n<div class=\"wp-block-getwid-advanced-heading is-style-default\" style=\"margin-top:10px\"><h2 class=\"wp-block-getwid-advanced-heading__content\">Historia de Chateau Marcel<\/h2><\/div>\r\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Ch\u00e2teau Marcel comenz\u00f3 modestamente como un conglomerado de peque\u00f1as casas construidas en el siglo IX en medio del antiguo pueblo de monta\u00f1a de Cesseras que debe su nombre al r\u00edo Cesse que formaba las hermosas gargantas justo detr\u00e1s del pueblo.<\/strong>  <\/p>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-black-color has-gold-background-color has-text-color has-background\" href=\"https:\/\/chateau-marcel.com\/es\/historia-del-castillo-marcel\/\">Descubre m\u00e1s<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<hr class=\"wp-block-separator\"\/>\n","protected":false},"excerpt":{"rendered":"Los c\u00e1taros (tambi\u00e9n conocidos como cathari del griego Katharoi para los \u00abpuros\u00bb) eran una secta religiosa medieval dualista del sur de Francia que floreci\u00f3 en el siglo XII d.C. y desafi\u00f3 la autoridad de la Iglesia Cat\u00f3lica. ","protected":false},"author":1,"featured_media":4253,"parent":0,"menu_order":90,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-4221","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/pages\/4221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/comments?post=4221"}],"version-history":[{"count":11,"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/pages\/4221\/revisions"}],"predecessor-version":[{"id":21908,"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/pages\/4221\/revisions\/21908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/media\/4253"}],"wp:attachment":[{"href":"https:\/\/chateau-marcel.com\/es\/wp-json\/wp\/v2\/media?parent=4221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}