{"id":8724,"date":"2019-12-21T09:56:30","date_gmt":"2019-12-21T09:56:30","guid":{"rendered":"https:\/\/chateau-marcel.com\/cascade-de-cubservies\/"},"modified":"2019-12-27T10:29:09","modified_gmt":"2019-12-27T10:29:09","slug":"cascade-de-cubservies","status":"publish","type":"post","link":"https:\/\/chateau-marcel.com\/fr\/cascade-de-cubservies\/","title":{"rendered":"Cascade de Cubservi\u00e8s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Un tr\u00e9sor de la Montagne Noire <\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Pour admirer la Cascade de Cubservi\u00e8s, rendez-vous au hameau du m\u00eame nom, au sommet d&rsquo;un pic rocheux.<br>Profitez d&rsquo;un panorama \u00e0 couper le souffle de la vall\u00e9e de Rieutort, au c\u0153ur de la Montagne Noire.<br><br>Vous pouvez \u00e9galement le voir depuis le beau village de Roquef\u00e8re. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le plateau de Sambr\u00e8s domine cette partie de la Montagne Noire avec sa couverture de r\u00e9sineux. Il draine plusieurs cours d&rsquo;eau qui se rencontrent et forment le Rieutort. La rivi\u00e8re se livre \u00e0 une faute de la roche pour former la Cascade de Cubservi\u00e8s. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il se compose de plusieurs projections et est de pr\u00e8s de 90 m\u00e8tres de haut, la partie visible atteint 35 m\u00e8tres! La vue depuis le petit hameau offre une vue enchanteresse.<br><br>La cascade est observ\u00e9e depuis le promontoire de Cubservi\u00e8s.<br><br>Pour appr\u00e9cier la richesse de cet environnement unique, allez faire de la randonn\u00e9e! <\/p>\n\n\n\n<div class=\"wp-block-getwid-images-slider has-arrows-inside has-dots-inside has-images-center\"><div class=\"wp-block-getwid-images-slider__wrapper\" data-effect=\"slide\" data-slides-show=\"1\" data-slides-show-laptop=\"1\" data-slides-show-tablet=\"1\" data-slides-show-mobile=\"1\" data-slides-scroll=\"1\" data-autoplay=\"false\" data-autoplay-speed=\"6000\" data-infinite=\"true\" data-animation-speed=\"800\" data-center-mode=\"false\" data-variable-width=\"false\" data-arrows=\"inside\" data-dots=\"inside\" data-spacing=\"none\"><div class=\"wp-block-getwid-images-slider__item\"><img decoding=\"async\" width=\"1280\" height=\"720\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade04-web.jpg\" alt=\"\" data-id=\"2355\" data-link=\"http:\/\/chateau-marcel.com\/cascade-de-cubservies\/cascade04-web\/\" class=\"wp-block-getwid-images-slider__image wp-image-2355\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade04-web.jpg 1280w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade04-web-300x169.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade04-web-1024x576.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade04-web-768x432.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade04-web-1170x658.jpg 1170w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/div><div class=\"wp-block-getwid-images-slider__item\"><img decoding=\"async\" width=\"1280\" height=\"854\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade01-web.jpg\" alt=\"\" data-id=\"2352\" data-link=\"http:\/\/chateau-marcel.com\/cascade-de-cubservies\/cascade01-web\/\" class=\"wp-block-getwid-images-slider__image wp-image-2352\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade01-web.jpg 1280w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade01-web-300x200.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade01-web-1024x683.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade01-web-768x512.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade01-web-1170x781.jpg 1170w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/div><div class=\"wp-block-getwid-images-slider__item\"><img decoding=\"async\" width=\"1280\" height=\"960\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade02-web.jpg\" alt=\"\" data-id=\"2353\" data-link=\"http:\/\/chateau-marcel.com\/cascade-de-cubservies\/cascade02-web\/\" class=\"wp-block-getwid-images-slider__image wp-image-2353\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade02-web.jpg 1280w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade02-web-300x225.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade02-web-1024x768.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade02-web-768x576.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade02-web-1170x878.jpg 1170w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/div><div class=\"wp-block-getwid-images-slider__item\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade03-web.jpg\" alt=\"\" data-id=\"2354\" data-link=\"http:\/\/chateau-marcel.com\/cascade-de-cubservies\/cascade03-web\/\" class=\"wp-block-getwid-images-slider__image wp-image-2354\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade03-web.jpg 1200w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade03-web-300x200.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade03-web-1024x683.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade03-web-768x512.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade03-web-1170x780.jpg 1170w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"wp-block-getwid-images-slider__item\"><img decoding=\"async\" width=\"1280\" height=\"960\" src=\"http:\/\/chateau-marcel.com\/wp-content\/uploads\/roquefere-web.jpg\" alt=\"Roquefere Roquefere\" data-id=\"2356\" data-link=\"http:\/\/chateau-marcel.com\/cascade-de-cubservies\/roquefere-web\/\" class=\"wp-block-getwid-images-slider__image wp-image-2356\" srcset=\"https:\/\/chateau-marcel.com\/wp-content\/uploads\/roquefere-web.jpg 1280w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/roquefere-web-300x225.jpg 300w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/roquefere-web-1024x768.jpg 1024w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/roquefere-web-768x576.jpg 768w, https:\/\/chateau-marcel.com\/wp-content\/uploads\/roquefere-web-1170x878.jpg 1170w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez combiner votre visite \u00e0 la cascade avec un arr\u00eat pr\u00e8s debij: Roquef\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce village typique, \u00e9tiquet\u00e9 \u00ab\u00a0village de caract\u00e8re\u00a0\u00bb, est situ\u00e9 dans un m\u00e9andre de la vall\u00e9e de Rieutort, dans le creux de la Montagne Noire. Il b\u00e9n\u00e9ficie d&rsquo;une protection naturelle. Riche d&rsquo;un ch\u00e2teau class\u00e9 monument historique depuis 1985, ce village est \u00e9galement le th\u00e9\u00e2tre du festival musical \u00ab\u00a0Jazz sous la ch\u00e2taigne\u00a0\u00bb chaque \u00e9t\u00e9. Un cadre idyllique pour une soir\u00e9e jazz !<br><br>Depuis les hauteurs de Roquef\u00e8re, admirez la belle Cascade de Cubservi\u00e8s, \u00e0 80 m\u00e8tres de cascade. Un site sauvage et imprenable ! Cliquez ici pour voir quelques photos.<br><br>Roquef\u00e8re est un site incontournable de la Montagne Noire ! Il offre aux amoureux de la nature des promenades de qualit\u00e9 au c\u0153ur d&rsquo;un environnement pr\u00e9serv\u00e9 et vert. <\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"CASCADE DE CUBSERVI\u00c8S\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/RlKbYQBcAuk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"Un tr\u00e9sor de la Montagne Noire","protected":false},"author":1,"featured_media":8730,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[193],"tags":[192,191],"class_list":["post-8724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hotspot-fr","tag-loisirs","tag-site-historique"],"jetpack_featured_media_url":"https:\/\/chateau-marcel.com\/wp-content\/uploads\/cascade-feat-im.jpg","_links":{"self":[{"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/posts\/8724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/comments?post=8724"}],"version-history":[{"count":5,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/posts\/8724\/revisions"}],"predecessor-version":[{"id":11503,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/posts\/8724\/revisions\/11503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/media\/8730"}],"wp:attachment":[{"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/media?parent=8724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/categories?post=8724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chateau-marcel.com\/fr\/wp-json\/wp\/v2\/tags?post=8724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}